{"id":624,"count":2,"description":"","link":"https:\/\/dancemix.co.uk\/brianmoleweddings\/tag\/steyning\/","name":"Steyning","slug":"steyning","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Posts related to on DJ Brian Mole<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Posts related to on DJ Brian Mole\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dancemix.co.uk\/brianmoleweddings\/tag\/steyning\/\" \/>\n<meta property=\"og:site_name\" content=\"DJ Brian Mole\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/dancemix.co.uk\\\/brianmoleweddings\\\/tag\\\/steyning\\\/\",\"url\":\"https:\\\/\\\/dancemix.co.uk\\\/brianmoleweddings\\\/tag\\\/steyning\\\/\",\"name\":\"Posts related to on DJ Brian Mole\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dancemix.co.uk\\\/brianmoleweddings\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dancemix.co.uk\\\/brianmoleweddings\\\/tag\\\/steyning\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dancemix.co.uk\\\/brianmoleweddings\\\/tag\\\/steyning\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dancemix.co.uk\\\/brianmoleweddings\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Steyning\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dancemix.co.uk\\\/brianmoleweddings\\\/#website\",\"url\":\"https:\\\/\\\/dancemix.co.uk\\\/brianmoleweddings\\\/\",\"name\":\"DJ Brian Mole\",\"description\":\"Brian Mole - Award Winning Wedding DJ and Master of Ceremonies based in West Sussex\",\"publisher\":{\"@id\":\"https:\\\/\\\/dancemix.co.uk\\\/brianmoleweddings\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dancemix.co.uk\\\/brianmoleweddings\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dancemix.co.uk\\\/brianmoleweddings\\\/#organization\",\"name\":\"DJ Brian Mole\",\"url\":\"https:\\\/\\\/dancemix.co.uk\\\/brianmoleweddings\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/dancemix.co.uk\\\/brianmoleweddings\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dancemix.co.uk\\\/brianmoleweddings\\\/wp-content\\\/uploads\\\/cropped-Brian-Mole-Wedding-DJ-Logo-400x136-1.jpg\",\"contentUrl\":\"https:\\\/\\\/dancemix.co.uk\\\/brianmoleweddings\\\/wp-content\\\/uploads\\\/cropped-Brian-Mole-Wedding-DJ-Logo-400x136-1.jpg\",\"width\":400,\"height\":133,\"caption\":\"DJ Brian Mole\"},\"image\":{\"@id\":\"https:\\\/\\\/dancemix.co.uk\\\/brianmoleweddings\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/weddingdjbrianmole\",\"https:\\\/\\\/www.pinterest.com\\\/topweddingdj\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/brianmole\\\/\",\"https:\\\/\\\/www.instagram.com\\\/djbrianmole\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@djbrianmole\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Posts related to on DJ Brian Mole","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_GB","og_type":"article","og_title":"Posts related to on DJ Brian Mole","og_url":"https:\/\/dancemix.co.uk\/brianmoleweddings\/tag\/steyning\/","og_site_name":"DJ Brian Mole","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/dancemix.co.uk\/brianmoleweddings\/tag\/steyning\/","url":"https:\/\/dancemix.co.uk\/brianmoleweddings\/tag\/steyning\/","name":"Posts related to on DJ Brian Mole","isPartOf":{"@id":"https:\/\/dancemix.co.uk\/brianmoleweddings\/#website"},"breadcrumb":{"@id":"https:\/\/dancemix.co.uk\/brianmoleweddings\/tag\/steyning\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/dancemix.co.uk\/brianmoleweddings\/tag\/steyning\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dancemix.co.uk\/brianmoleweddings\/"},{"@type":"ListItem","position":2,"name":"Steyning"}]},{"@type":"WebSite","@id":"https:\/\/dancemix.co.uk\/brianmoleweddings\/#website","url":"https:\/\/dancemix.co.uk\/brianmoleweddings\/","name":"DJ Brian Mole","description":"Brian Mole - Award Winning Wedding DJ and Master of Ceremonies based in West Sussex","publisher":{"@id":"https:\/\/dancemix.co.uk\/brianmoleweddings\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dancemix.co.uk\/brianmoleweddings\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/dancemix.co.uk\/brianmoleweddings\/#organization","name":"DJ Brian Mole","url":"https:\/\/dancemix.co.uk\/brianmoleweddings\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/dancemix.co.uk\/brianmoleweddings\/#\/schema\/logo\/image\/","url":"https:\/\/dancemix.co.uk\/brianmoleweddings\/wp-content\/uploads\/cropped-Brian-Mole-Wedding-DJ-Logo-400x136-1.jpg","contentUrl":"https:\/\/dancemix.co.uk\/brianmoleweddings\/wp-content\/uploads\/cropped-Brian-Mole-Wedding-DJ-Logo-400x136-1.jpg","width":400,"height":133,"caption":"DJ Brian Mole"},"image":{"@id":"https:\/\/dancemix.co.uk\/brianmoleweddings\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/weddingdjbrianmole","https:\/\/www.pinterest.com\/topweddingdj\/","https:\/\/www.youtube.com\/user\/brianmole\/","https:\/\/www.instagram.com\/djbrianmole\/","https:\/\/www.tiktok.com\/@djbrianmole"]}]}},"_links":{"self":[{"href":"https:\/\/dancemix.co.uk\/brianmoleweddings\/wp-json\/wp\/v2\/tags\/624","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dancemix.co.uk\/brianmoleweddings\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/dancemix.co.uk\/brianmoleweddings\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/dancemix.co.uk\/brianmoleweddings\/wp-json\/wp\/v2\/posts?tags=624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}